{"id":8001,"date":"2020-06-02T13:46:03","date_gmt":"2020-06-02T11:46:03","guid":{"rendered":"https:\/\/mugardos.gal\/eventos\/quedanacasa-8-de-junio\/"},"modified":"2020-06-02T13:48:17","modified_gmt":"2020-06-02T11:48:17","slug":"quedanacasa-8-de-junio","status":"publish","type":"lsvr_event","link":"https:\/\/mugardos.gal\/es\/eventos\/quedanacasa-8-de-junio\/","title":{"rendered":"#QUEDANACASA 8 DE JUNIO"},"content":{"rendered":"<p id=\"contenedor\" class=\"textarea unknown\" style=\"text-align: justify;\">Las Concejal\u00edas de Deporte y Cultura proponen actividades para hacer con los m\u00e1s peque\u00f1os de la casa durante esta cuarentena. Hoy visitamos la tumba de Ramses VI, en la orilla del Nilo, una de las mejores conservadas dentro del Valle de los Reyes<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" class=\"alignnone wp-image-602\" src=\"https:\/\/mugardos.gal\/wp-content\/uploads\/2020\/03\/web.png\" alt=\"\" width=\"30\" height=\"30\" \/> En el siguiente enlace puede acceder a la p\u00e1gina oficial: <a href=\"https:\/\/describingegypt.com\/tours\/ramessesvi\/\">https:\/\/describingegypt.com\/tours\/ramessesvi\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las Concejal\u00edas de Deporte y Cultura proponen actividades para hacer con los m\u00e1s peque\u00f1os de la casa durante esta cuarentena. Hoy visitamos la tumba de Ramses VI, en la orilla del Nilo, una de las mejores conservadas dentro del Valle de los Reyes En el siguiente enlace puede acceder a la p\u00e1gina oficial: https:\/\/describingegypt.com\/tours\/ramessesvi\/<\/p>\n","protected":false},"author":4,"featured_media":7993,"template":"","meta":[],"lsvr_event_cat":[60,67,65],"lsvr_event_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>#QUEDANACASA 8 DE JUNIO - Concello de Mugardos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mugardos.gal\/es\/eventos\/quedanacasa-8-de-junio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#QUEDANACASA 8 DE JUNIO - Concello de Mugardos\" \/>\n<meta property=\"og:description\" content=\"Las Concejal\u00edas de Deporte y Cultura proponen actividades para hacer con los m\u00e1s peque\u00f1os de la casa durante esta cuarentena. Hoy visitamos la tumba de Ramses VI, en la orilla del Nilo, una de las mejores conservadas dentro del Valle de los Reyes En el siguiente enlace puede acceder a la p\u00e1gina oficial: https:\/\/describingegypt.com\/tours\/ramessesvi\/\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mugardos.gal\/es\/eventos\/quedanacasa-8-de-junio\/\" \/>\n<meta property=\"og:site_name\" content=\"Concello de Mugardos\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-02T11:48:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mugardos.gal\/wp-content\/uploads\/2020\/06\/Rams\u00e9s.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"540\" \/>\n\t<meta property=\"og:image:height\" content=\"282\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mugardos.gal\/#website\",\"url\":\"https:\/\/mugardos.gal\/\",\"name\":\"Concello de Mugardos\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mugardos.gal\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/mugardos.gal\/es\/eventos\/quedanacasa-8-de-junio\/#primaryimage\",\"url\":\"https:\/\/mugardos.gal\/wp-content\/uploads\/2020\/06\/Rams\u00e9s.jpg\",\"contentUrl\":\"https:\/\/mugardos.gal\/wp-content\/uploads\/2020\/06\/Rams\u00e9s.jpg\",\"width\":540,\"height\":282},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mugardos.gal\/es\/eventos\/quedanacasa-8-de-junio\/#webpage\",\"url\":\"https:\/\/mugardos.gal\/es\/eventos\/quedanacasa-8-de-junio\/\",\"name\":\"#QUEDANACASA 8 DE JUNIO - Concello de Mugardos\",\"isPartOf\":{\"@id\":\"https:\/\/mugardos.gal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mugardos.gal\/es\/eventos\/quedanacasa-8-de-junio\/#primaryimage\"},\"datePublished\":\"2020-06-02T11:46:03+00:00\",\"dateModified\":\"2020-06-02T11:48:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mugardos.gal\/es\/eventos\/quedanacasa-8-de-junio\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mugardos.gal\/es\/eventos\/quedanacasa-8-de-junio\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mugardos.gal\/es\/eventos\/quedanacasa-8-de-junio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/mugardos.gal\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EVENTOS\",\"item\":\"https:\/\/mugardos.gal\/eventos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"#QUEDANACASA 8 DE JUNIO\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#QUEDANACASA 8 DE JUNIO - Concello de Mugardos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mugardos.gal\/es\/eventos\/quedanacasa-8-de-junio\/","og_locale":"es_ES","og_type":"article","og_title":"#QUEDANACASA 8 DE JUNIO - Concello de Mugardos","og_description":"Las Concejal\u00edas de Deporte y Cultura proponen actividades para hacer con los m\u00e1s peque\u00f1os de la casa durante esta cuarentena. Hoy visitamos la tumba de Ramses VI, en la orilla del Nilo, una de las mejores conservadas dentro del Valle de los Reyes En el siguiente enlace puede acceder a la p\u00e1gina oficial: https:\/\/describingegypt.com\/tours\/ramessesvi\/","og_url":"https:\/\/mugardos.gal\/es\/eventos\/quedanacasa-8-de-junio\/","og_site_name":"Concello de Mugardos","article_modified_time":"2020-06-02T11:48:17+00:00","og_image":[{"width":540,"height":282,"url":"https:\/\/mugardos.gal\/wp-content\/uploads\/2020\/06\/Rams\u00e9s.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/mugardos.gal\/#website","url":"https:\/\/mugardos.gal\/","name":"Concello de Mugardos","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mugardos.gal\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mugardos.gal\/es\/eventos\/quedanacasa-8-de-junio\/#primaryimage","url":"https:\/\/mugardos.gal\/wp-content\/uploads\/2020\/06\/Rams\u00e9s.jpg","contentUrl":"https:\/\/mugardos.gal\/wp-content\/uploads\/2020\/06\/Rams\u00e9s.jpg","width":540,"height":282},{"@type":"WebPage","@id":"https:\/\/mugardos.gal\/es\/eventos\/quedanacasa-8-de-junio\/#webpage","url":"https:\/\/mugardos.gal\/es\/eventos\/quedanacasa-8-de-junio\/","name":"#QUEDANACASA 8 DE JUNIO - Concello de Mugardos","isPartOf":{"@id":"https:\/\/mugardos.gal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mugardos.gal\/es\/eventos\/quedanacasa-8-de-junio\/#primaryimage"},"datePublished":"2020-06-02T11:46:03+00:00","dateModified":"2020-06-02T11:48:17+00:00","breadcrumb":{"@id":"https:\/\/mugardos.gal\/es\/eventos\/quedanacasa-8-de-junio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mugardos.gal\/es\/eventos\/quedanacasa-8-de-junio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mugardos.gal\/es\/eventos\/quedanacasa-8-de-junio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mugardos.gal\/es\/"},{"@type":"ListItem","position":2,"name":"EVENTOS","item":"https:\/\/mugardos.gal\/eventos\/"},{"@type":"ListItem","position":3,"name":"#QUEDANACASA 8 DE JUNIO"}]}]}},"_links":{"self":[{"href":"https:\/\/mugardos.gal\/es\/wp-json\/wp\/v2\/lsvr_event\/8001"}],"collection":[{"href":"https:\/\/mugardos.gal\/es\/wp-json\/wp\/v2\/lsvr_event"}],"about":[{"href":"https:\/\/mugardos.gal\/es\/wp-json\/wp\/v2\/types\/lsvr_event"}],"author":[{"embeddable":true,"href":"https:\/\/mugardos.gal\/es\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/mugardos.gal\/es\/wp-json\/wp\/v2\/lsvr_event\/8001\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mugardos.gal\/es\/wp-json\/wp\/v2\/media\/7993"}],"wp:attachment":[{"href":"https:\/\/mugardos.gal\/es\/wp-json\/wp\/v2\/media?parent=8001"}],"wp:term":[{"taxonomy":"lsvr_event_cat","embeddable":true,"href":"https:\/\/mugardos.gal\/es\/wp-json\/wp\/v2\/lsvr_event_cat?post=8001"},{"taxonomy":"lsvr_event_tag","embeddable":true,"href":"https:\/\/mugardos.gal\/es\/wp-json\/wp\/v2\/lsvr_event_tag?post=8001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}